{"id":4749,"date":"2022-11-09T06:33:07","date_gmt":"2022-11-09T06:33:07","guid":{"rendered":"https:\/\/elizar.ch\/product\/collier-janet\/"},"modified":"2023-06-09T14:00:31","modified_gmt":"2023-06-09T14:00:31","slug":"collier-janet","status":"publish","type":"product","link":"https:\/\/elizar.ch\/en\/product\/collier-janet\/","title":{"rendered":"Collier Janet"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1514,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[156,152],"product_tag":[],"class_list":["post-4749","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-necklaces","product_cat-women-collection"],"_links":{"self":[{"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/product\/4749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/comments?post=4749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/media\/1514"}],"wp:attachment":[{"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/media?parent=4749"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/product_cat?post=4749"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/product_tag?post=4749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}