{"id":4486,"date":"2022-11-09T06:34:18","date_gmt":"2022-11-09T06:34:18","guid":{"rendered":"https:\/\/elizar.ch\/product\/collier-esperanza\/"},"modified":"2023-06-09T10:32:29","modified_gmt":"2023-06-09T10:32:29","slug":"collier-esperanza","status":"publish","type":"product","link":"https:\/\/elizar.ch\/en\/product\/collier-esperanza\/","title":{"rendered":"Collier Esperanza"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2943,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":""},"product_cat":[156,152],"product_tag":[],"class_list":["post-4486","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-necklaces","product_cat-women-collection"],"_links":{"self":[{"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/product\/4486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/comments?post=4486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/media\/2943"}],"wp:attachment":[{"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/media?parent=4486"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/product_cat?post=4486"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/elizar.ch\/en\/wp-json\/wp\/v2\/product_tag?post=4486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}